{"id":9839,"date":"2024-11-21T13:33:40","date_gmt":"2024-11-21T12:33:40","guid":{"rendered":"https:\/\/www.imbc.be\/roosens-betons-une-histoire-familiale-riche-de-115-ans\/"},"modified":"2024-11-21T13:33:40","modified_gmt":"2024-11-21T12:33:40","slug":"roosens-betons-une-histoire-familiale-riche-de-115-ans","status":"publish","type":"post","link":"https:\/\/www.imbc.be\/en\/roosens-betons-une-histoire-familiale-riche-de-115-ans\/","title":{"rendered":"Roosens B\u00e9tons, une histoire familiale riche de 115 ans"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Roosens B\u00e9tons, une histoire familiale riche de 115 ans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4 g\u00e9n\u00e9rations de savoir-faire et d\u2019esprit d\u2019entreprendre mais surtout un incroyable d\u00e9veloppement amen\u00e9 par la g\u00e9n\u00e9ration actuelle s\u2019inscrivant dans l\u2019\u00e9conomie r\u00e9g\u00e9n\u00e9rative.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De \u00ab Neutre en CO2 \u00bb pour partie par compensation depuis plus de 10 ans, Roosens Betons vise la d\u00e9carbonation de ses activit\u00e9s sans compensation&nbsp;!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.linkedin.com\/posts\/sylvie-creteur-33209aa9_charleroi-mons-liaeyge-activity-7158745724141137920--oCV?utm_source=share&amp;utm_medium=member_desktop\"><img loading=\"lazy\" decoding=\"async\" width=\"30\" height=\"28\" src=\"https:\/\/www.imbc.be\/wp-content\/uploads\/2024\/11\/logo-linkedin-1-2.png\" alt=\"\" class=\"wp-image-7571\" style=\"object-fit:cover\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roosens B\u00e9tons, une histoire familiale riche de 115 ans. 4 g\u00e9n\u00e9rations de savoir-faire et d\u2019esprit d\u2019entreprendre mais surtout un incroyable d\u00e9veloppement amen\u00e9 par la g\u00e9n\u00e9ration actuelle s\u2019inscrivant dans l\u2019\u00e9conomie r\u00e9g\u00e9n\u00e9rative. De \u00ab Neutre en CO2 \u00bb pour partie par compensation depuis plus de 10 ans, Roosens Betons vise la d\u00e9carbonation de ses activit\u00e9s sans compensation&nbsp;!<\/p>\n","protected":false},"author":13,"featured_media":7610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[263],"tags":[],"class_list":["post-9839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/posts\/9839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/comments?post=9839"}],"version-history":[{"count":0,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/posts\/9839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/media\/7610"}],"wp:attachment":[{"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/media?parent=9839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/categories?post=9839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/tags?post=9839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}