{"id":9819,"date":"2024-11-22T11:00:19","date_gmt":"2024-11-22T10:00:19","guid":{"rendered":"https:\/\/www.imbc.be\/parole-dun-administrateur-bruno-colmant\/"},"modified":"2024-11-22T11:00:19","modified_gmt":"2024-11-22T10:00:19","slug":"parole-dun-administrateur-bruno-colmant","status":"publish","type":"post","link":"https:\/\/www.imbc.be\/en\/parole-dun-administrateur-bruno-colmant\/","title":{"rendered":"Parole d&#8217;un administrateur : Bruno Colmant"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Faites preuve d\u2019audace et n\u2019h\u00e9sitez pas \u00e0 frapper \u00e0 la porte de votre invest&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bruno Colmant parle de sa vision sur les invests et principalement d\u2019IMBC dont il est administrateur. Venant d\u2019une famille d\u2019enseignants, l\u2019\u00e9conomiste s\u2019est r\u00e9v\u00e9l\u00e9 \u00eatre un entrepreneur dans l\u2019\u00e2me au fil du temps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Retrouvez son t\u00e9moignage ci-dessous.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.linkedin.com\/posts\/groupeimbc_imbc-entreprendre-activity-7206928392816865285-wPsz?utm_source=share&amp;utm_medium=member_desktop\"><img loading=\"lazy\" decoding=\"async\" width=\"30\" height=\"28\" src=\"https:\/\/www.imbc.be\/wp-content\/uploads\/2024\/11\/logo-linkedin-1-2.png\" alt=\"\" class=\"wp-image-7571\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&nbsp;Faites preuve d\u2019audace et n\u2019h\u00e9sitez pas \u00e0 frapper \u00e0 la porte de votre invest&nbsp;\u00bb. Bruno Colmant parle de sa vision sur les invests et principalement d\u2019IMBC dont il est administrateur. Venant d\u2019une famille d\u2019enseignants, l\u2019\u00e9conomiste s\u2019est r\u00e9v\u00e9l\u00e9 \u00eatre un entrepreneur dans l\u2019\u00e2me au fil du temps. Retrouvez son t\u00e9moignage ci-dessous.<\/p>\n","protected":false},"author":13,"featured_media":7673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[263],"tags":[],"class_list":["post-9819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/posts\/9819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/comments?post=9819"}],"version-history":[{"count":0,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/posts\/9819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/media\/7673"}],"wp:attachment":[{"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/media?parent=9819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/categories?post=9819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.imbc.be\/en\/wp-json\/wp\/v2\/tags?post=9819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}